{"id":4380,"date":"2018-11-12T08:25:52","date_gmt":"2018-11-12T07:25:52","guid":{"rendered":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/?p=4380"},"modified":"2018-11-12T08:26:31","modified_gmt":"2018-11-12T07:26:31","slug":"scheda-585","status":"publish","type":"post","link":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/scheda-585\/","title":{"rendered":"Scheda 585"},"content":{"rendered":"<p><a title=\"I docenti con specializzazione polivalente debbono avere le competenze per trattare con le differenti situazioni di disabilit\u00e0 (CdS 5851\/18)\" href=\"https:\/\/aipd.it\/aipd_scuola\/i-docenti-con-specializzazione-polivalente-debbono-avere-le-competenze-per-trattare-con-le-differenti-situazioni-di-disabilita-cds-585118\/\" rel=\"bookmark\">I docenti con specializzazione polivalente debbono avere le competenze per trattare con le differenti situazioni di disabilit\u00e0 (CdS 5851\/18)<\/a><\/p>\n<h4 class=\"post-title\"><!--more--><br \/>\n<img loading=\"lazy\" src=\"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-content\/uploads\/2013\/12\/1.jpg\" alt=\"1\" width=\"450\" height=\"120\"><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>I docenti con specializzazione polivalente debbono avere le competenze per trattare con le differenti situazioni di disabilit\u00e0 (CdS 5851\/18)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[55],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/posts\/4380"}],"collection":[{"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/comments?post=4380"}],"version-history":[{"count":2,"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/posts\/4380\/revisions"}],"predecessor-version":[{"id":4386,"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/posts\/4380\/revisions\/4386"}],"wp:attachment":[{"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/media?parent=4380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/categories?post=4380"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.integrazionepetaloazzurro.org\/anew\/wp-json\/wp\/v2\/tags?post=4380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}